{"id":2536,"date":"2024-11-17T04:05:09","date_gmt":"2024-11-17T04:05:09","guid":{"rendered":"https:\/\/dewinelabs.wpenginepowered.com\/use-cases\/"},"modified":"2026-04-20T09:30:29","modified_gmt":"2026-04-20T09:30:29","slug":"anwendungen","status":"publish","type":"page","link":"https:\/\/dewinelabs.com\/de\/anwendungen\/","title":{"rendered":"Anwendungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2536\" class=\"elementor elementor-2536 elementor-126\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bccee12 e-flex e-con-boxed e-con e-parent\" data-id=\"bccee12\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-efd95d5 e-con-full e-flex e-con e-child\" data-id=\"efd95d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-96c7178 e-con-full e-flex e-con e-child\" data-id=\"96c7178\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01b812f elementor-widget__width-auto animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"01b812f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Anwendungen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bb8db1 e-con-full e-flex e-con e-child\" data-id=\"1bb8db1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbe4154 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"bbe4154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ma\u00dfgeschneiderte Bluetooth LE L\u00f6sungen f\u00fcr deine  <span class=\"gradient-span\">Branchenanforderungen<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf9a8e3 e-con-full e-flex e-con e-child\" data-id=\"bf9a8e3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-287e125 elementor-widget elementor-widget-text-editor\" data-id=\"287e125\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir entwickeln branchen-spezifische Bluetooth LE L\u00f6sungen, die alle deine Kommunikationsprobleme l\u00f6sen. Unsere Produkte bieten h\u00f6chste Leistung und Zuverl\u00e4ssigkeit, auch unter schwierigsten Bedingungen. Damit stellen wir sicher, dass dein System st\u00e4ndig zuverl\u00e4ssig, effizient und skalierbar bleibt. Entdecke die Vorteile unserer DEWINE Labs Technologie in verschiedenen Industrien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a7ee97 btn-arrow elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"2a7ee97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/dewinelabs.com\/de\/kontakt\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Gespr\u00e4ch buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53b118a e-con-full e-flex e-con e-child\" data-id=\"53b118a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ac6b88 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"3ac6b88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/DSC07089-copy.webp\" class=\"attachment-full size-full wp-image-2423\" alt=\"DSC07089 copy\" srcset=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/DSC07089-copy.webp 1600w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/DSC07089-copy-300x200.webp 300w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/DSC07089-copy-1024x683.webp 1024w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/DSC07089-copy-768x512.webp 768w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/DSC07089-copy-1536x1024.webp 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-104fb61 e-flex e-con-boxed e-con e-parent\" data-id=\"104fb61\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f070e9 elementor-widget elementor-widget-heading\" data-id=\"7f070e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Anwendungsf\u00e4lle umfassen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c892634 e-con-full e-grid e-con e-child\" data-id=\"c892634\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-ee5f38b e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"ee5f38b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abdf651 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"abdf651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/photo-automobile-production-line-welding-car-body-modern-car-assembly-plant-auto-industry-scaled.jpg\" class=\"attachment-full size-full wp-image-2406\" alt=\"photo automobile production line welding car body modern car assembly plant auto industry scaled\" srcset=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/photo-automobile-production-line-welding-car-body-modern-car-assembly-plant-auto-industry-scaled.jpg 2560w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/photo-automobile-production-line-welding-car-body-modern-car-assembly-plant-auto-industry-300x200.jpg 300w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/photo-automobile-production-line-welding-car-body-modern-car-assembly-plant-auto-industry-1024x683.jpg 1024w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/photo-automobile-production-line-welding-car-body-modern-car-assembly-plant-auto-industry-768x512.jpg 768w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/photo-automobile-production-line-welding-car-body-modern-car-assembly-plant-auto-industry-1536x1025.jpg 1536w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/photo-automobile-production-line-welding-car-body-modern-car-assembly-plant-auto-industry-2048x1366.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c27201 e-con-full e-flex e-con e-child\" data-id=\"4c27201\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f7b599 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"2f7b599\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Industrieautomatisierung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c65dad elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"0c65dad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vom Ersetzen serieller Kabel bis hin zur Koordination ganzer Flotten von AGVs bietet unsere Bluetooth LE Technologie unvergleichliche Zuverl\u00e4ssigkeit in anspruchsvollen Industrieumgebungen. Erfahre, wie wir daf\u00fcr sorgen, dass deine Systeme auch in Umgebungen mit schweren Maschinen und starken St\u00f6rsignalen reibungslos laufen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c8964d btn-arrow elementor-widget elementor-widget-button\" data-id=\"4c8964d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/de\/anwendungen\/industrielle-automatisierung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6168197 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"6168197\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6300fcf elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"6300fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"668\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/male-person-pays-checkout-grocery-store-man-buying-beverages-products-market-copy.webp\" class=\"attachment-full size-full wp-image-2385\" alt=\"male person pays checkout grocery store man buying beverages products market copy\" srcset=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/male-person-pays-checkout-grocery-store-man-buying-beverages-products-market-copy.webp 1000w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/male-person-pays-checkout-grocery-store-man-buying-beverages-products-market-copy-300x200.webp 300w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/male-person-pays-checkout-grocery-store-man-buying-beverages-products-market-copy-768x513.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e012dfc e-con-full e-flex e-con e-child\" data-id=\"e012dfc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a525a44 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"a525a44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Smart Retail<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04125e8 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"04125e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Verwaltung von bis zu 100.000 Ger\u00e4ten wie elektronischen Preisschildern erfordert eine besonders robuste drahtlose Kommunikation. Unsere Bluetooth LE Technologie stellt sicher, dass jedes Ger\u00e4t reibungslos funktioniert \u2013 selbst in stark frequentierten Verkaufsfl\u00e4chen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e9f5c btn-arrow elementor-widget elementor-widget-button\" data-id=\"40e9f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/de\/anwendungen\/smart-retail\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-652b082 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"652b082\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc0e2f9 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"fc0e2f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1368\" height=\"912\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/shock-wave-therapy-device-with-male-doctor-hands-rubber-gloves.webp\" class=\"attachment-full size-full wp-image-2420\" alt=\"shock wave therapy device with male doctor hands rubber gloves\" srcset=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/shock-wave-therapy-device-with-male-doctor-hands-rubber-gloves.webp 1368w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/shock-wave-therapy-device-with-male-doctor-hands-rubber-gloves-300x200.webp 300w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/shock-wave-therapy-device-with-male-doctor-hands-rubber-gloves-1024x683.webp 1024w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/shock-wave-therapy-device-with-male-doctor-hands-rubber-gloves-768x512.webp 768w\" sizes=\"(max-width: 1368px) 100vw, 1368px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8004003 e-con-full e-flex e-con e-child\" data-id=\"8004003\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d50dce elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"0d50dce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Medizintechnik<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-639239d elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"639239d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei lebenskritischen Anwendungen ist ein zuverl\u00e4ssiger Datentransfer unverzichtbar. Unsere Bluetooth LE Technologie unterst\u00fctzt die drahtlose Kommunikation zwischen medizinischen Ger\u00e4ten und sorgt mit sicherem und zeitgerechtem Datenaustausch f\u00fcr Patientensicherheit<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6609aa1 btn-arrow elementor-widget elementor-widget-button\" data-id=\"6609aa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/de\/anwendungen\/medizintechnik\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbd70f1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"cbd70f1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c677bf elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"7c677bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/warehouse-worker-scanning-box-warehouse.webp\" class=\"attachment-full size-full wp-image-2435\" alt=\"warehouse worker scanning box warehouse\" srcset=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/warehouse-worker-scanning-box-warehouse.webp 1500w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/warehouse-worker-scanning-box-warehouse-300x200.webp 300w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/warehouse-worker-scanning-box-warehouse-1024x683.webp 1024w, https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/12\/warehouse-worker-scanning-box-warehouse-768x512.webp 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-126d4b4 e-con-full e-flex e-con e-child\" data-id=\"126d4b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69b8f60 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"69b8f60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tracking and Monitoring<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20f0e6b elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"20f0e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Verfolge und \u00fcberwache sensible Assets effizient in Krankenh\u00e4usern, Lagern und Logistikzentren. Unsere Bluetooth LE L\u00f6sungen erm\u00f6glichen pr\u00e4zises Positionstracking und bieten eine lange Batterielaufzeit f\u00fcr kontinuierliche \u00dcberwachung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-510cfa3 btn-arrow elementor-widget elementor-widget-button\" data-id=\"510cfa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/de\/anwendungen\/asset-tracking-management\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2d9579 e-con-full e-flex e-con e-parent\" data-id=\"f2d9579\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-aa513fa e-flex e-con-boxed e-con e-child\" data-id=\"aa513fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-684fe26 e-con-full e-flex e-con e-child\" data-id=\"684fe26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-2e732bd e-con-full e-flex e-con e-child\" data-id=\"2e732bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a61b15c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"a61b15c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dein Bluetooth-Partner f\u00fcr <span class=\"gradient-span\">zeit- und sicherheitskritische Anwendungen<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4712719 elementor-widget elementor-widget-text-editor\" data-id=\"4712719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Von Industrieautomation und Medizintechnik \u00fcber mobile Robotik bis hin zu flexiblen Fertigungslinien: DEWINE Labs liefert dir Bluetooth LE Kommunikation, die deine Systeme zuverl\u00e4ssig, sicher und effizient macht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-982a5cf btn-arrow elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"982a5cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/dewinelabs.com\/de\/kontakt\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Gespr\u00e4ch buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-794bbf4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"794bbf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/cta_visual_white_no_grid-1.svg\" class=\"attachment-full size-full wp-image-2396\" alt=\"cta visual white no grid 1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4cd3b2 e-flex e-con-boxed e-con e-parent\" data-id=\"a4cd3b2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4103882 e-con-full e-flex e-con e-child\" data-id=\"4103882\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-974ffc5 e-con-full e-flex e-con e-child\" data-id=\"974ffc5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2faa87a elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-shortcode\" data-id=\"2faa87a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\t\tvar gCaptchaSibWidget;\n                        var onloadSibCallbackInvisible = function () {\n\n                            var element = document.getElementsByClassName('sib-default-btn');\n                            var countInvisible = 0;\n                            var indexArray = [];\n                            jQuery('.sib-default-btn').each(function (index, el) {\n                                if ((jQuery(el).attr('id') == \"invisible\")) {\n                                    indexArray[countInvisible] = index;\n                                    countInvisible++\n                                }\n                            });\n\n                            jQuery('.invi-recaptcha').each(function (index, el) {\n                                grecaptcha.render(element[indexArray[index]], {\n                                    'sitekey': jQuery(el).attr('data-sitekey'),\n                                    'callback': sibVerifyCallback,\n                                });\n                            });\n                        };\n\t\t\t\t\t<\/script>\n\t\t\t\t\t                <script src=\"https:\/\/www.google.com\/recaptcha\/api.js?onload=onloadSibCallbackInvisible&render=explicit\" async defer><\/script>\n\t\t\t\t\n\t\t\t<form id=\"sib_signup_form_2\" method=\"post\" class=\"sib_signup_form\">\n\t\t\t\t<div class=\"sib_loader\" style=\"display:none;\"><img\n\t\t\t\t\t\t\tsrc=\"https:\/\/dewinelabs.com\/wp-includes\/images\/spinner.gif\" alt=\"loader\"><\/div>\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_action\" value=\"subscribe_form_submit\">\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_id\" value=\"2\">\n                <input type=\"hidden\" name=\"sib_form_alert_notice\" value=\"Du hast vergessen, ein Pflichtfeld* auszuf\u00fcllen.\">\n                <input type=\"hidden\" name=\"sib_form_invalid_email_notice\" value=\"Die angegebenen Informationen sind ung\u00fcltig. Bitte \u00fcberpr\u00fcfe das Format der Felder und versuche es erneut.\">\n                <input type=\"hidden\" name=\"sib_security\" value=\"0eef6e38ad\">\n\t\t\t\t<div class=\"sib_signup_box_inside_2\">\n\t\t\t\t\t<div style=\"\/*display:none*\/\" class=\"sib_msg_disp\">\n\t\t\t\t\t<\/div>\n                                            <div id=\"sib_captcha_invisible\" class=\"invi-recaptcha\" data-sitekey=\"6LepdMorAAAAAABzioBAkTCNv5dvm6y4Dz6UnHh_\"><\/div>\n                    \t\t\t\t\t<h2>Newsletter<\/h2>\r\n\r\n<p>Melde dich f\u00fcr unseren Newsletter an, um auf dem Laufenden zu bleiben.<\/p>\r\n\r\n<p class=\"sib-email-area\">\r\n    <label>E-Mail*<\/label>\r\n    <input type=\"email\" class=\"sib-email-area\" name=\"email\" required=\"required\" placeholder=\"Gib hier bitte deine E-Mail-Adresse ein.\">\r\n<\/p>\r\n<p class=\"sib-VORNAME-area\">\r\n    <label>Vorname<\/label>\r\n    <input type=\"text\" class=\"sib-VORNAME-area\" name=\"VORNAME\" placeholder=\"Gib hier bitte deinen Vornamen ein.\">\r\n<\/p>\r\n<p class=\"sib-NACHNAME-area\">\r\n    <label>Nachname<\/label>\r\n    <input type=\"text\" class=\"sib-NACHNAME-area\" name=\"NACHNAME\" placeholder=\"Gib hier bitte deinen Nachnamen ein.\">\r\n<\/p>\r\n\r\n<p class=\"sib-COMPANY-area\"> \r\n    <label class=\"sib-COMPANY-area\">Firma<\/label> \r\n    <input type=\"text\" class=\"sib-COMPANY-area\" name=\"COMPANY\" placeholder=\"Gib hier bitte das Unternehmen ein, f\u00fcr das du arbeitest.\"> \r\n<\/p>\r\n<p>\r\n\r\n<input type=\"checkbox\" name=\"terms\" required=\"required\">Ich m\u00f6chte den Newsletter erhalten und akzeptiere die <a href=\"https:\/\/dewinelabs.com\/de\/datenschutzerklarung\/\">Datenschutzerkl\u00e4rung<\/a>.*\r\n\r\n<p>Du musst den Datenschutzbestimmungen der DEWINE Labs GmbH zustimmen, um dich f\u00fcr den Newsletter anzumelden.<\/p>\r\n\r\n<input type=\"submit\" id=\"invisible\" class=\"sib-default-btn\" value=\"Anmelden\">\r\n<\/p>\r\n\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<style>\n\t\t\t\tform#sib_signup_form_2 p.sib-alert-message {\n    padding: 6px 12px;\n    margin-bottom: 20px;\n    border: 1px solid transparent;\n    border-radius: 4px;\n    -webkit-box-sizing: border-box;\n    -moz-box-sizing: border-box;\n    box-sizing: border-box;\n}\nform#sib_signup_form_2 p.sib-alert-message-error {\n    background-color: #f2dede;\n    border-color: #ebccd1;\n    color: #a94442;\n}\nform#sib_signup_form_2 p.sib-alert-message-success {\n    background-color: #dff0d8;\n    border-color: #d6e9c6;\n    color: #3c763d;\n}\nform#sib_signup_form_2 p.sib-alert-message-warning {\n    background-color: #fcf8e3;\n    border-color: #faebcc;\n    color: #8a6d3b;\n}\n\t\t\t<\/style>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f9c8f8 elementor-widget elementor-widget-spacer\" data-id=\"8f9c8f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dcd462 elementor-widget elementor-widget-spacer\" data-id=\"9dcd462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26423f4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"26423f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wissensbasis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-006934d e-con-full stagger-fade e-flex e-con e-child\" data-id=\"006934d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-db5d6d6 e-con-full stagger-grid-item e-flex e-con e-child\" data-id=\"db5d6d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a07496f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a07496f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"30\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/Products-icon.svg\" class=\"attachment-full size-full wp-image-2375\" alt=\"Products icon\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac8e1ba elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"ac8e1ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/de\/produkte\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unsere Produkte<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-766ff4f elementor-widget elementor-widget-text-editor\" data-id=\"766ff4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entdecke unsere innovativen Bluetooth LE L\u00f6sungen, die Bluetooth-Chips in leistungsstarke Werkzeuge f\u00fcr nahtlose, zuverl\u00e4ssige und effiziente drahtlose Kommunikation verwandeln.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-520ed31 e-con-full stagger-grid-item e-flex e-con e-child\" data-id=\"520ed31\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-869af14 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"869af14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"30\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/Blog-icon.svg\" class=\"attachment-full size-full wp-image-2377\" alt=\"Blog icon\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb920c5 elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"fb920c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/de\/ressourcen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ressourcen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c3aa9 elementor-widget elementor-widget-text-editor\" data-id=\"35c3aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Verpasse keine Insights, Updates und Expertenmeinungen rund um die neuesten Entwicklungen in der Bluetooth-Technologie und drahtlosen Kommunikation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ba2e36 e-con-full stagger-grid-item elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"7ba2e36\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fa24c0 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4fa24c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"30\" src=\"https:\/\/dewinelabs.com\/wp-content\/uploads\/2024\/11\/Blog-icon.svg\" class=\"attachment-full size-full wp-image-2377\" alt=\"Blog icon\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18b6a25 elementor-align-justify elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"18b6a25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/de\/blog\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M5.5037 5.28587C5.78262 5.56479 5.78262 6.01776 5.5037 6.29669L1.21942 10.581C0.940493 10.8599 0.48752 10.8599 0.208595 10.581C-0.0703293 10.302 -0.0703293 9.84907 0.208595 9.57015L3.98858 5.79016L0.210827 2.01018C-0.0680978 1.73125 -0.0680978 1.27828 0.210827 0.999355C0.489751 0.72043 0.942725 0.72043 1.22165 0.999355L5.50593 5.28363L5.5037 5.28587Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Our Blog<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7fe11c elementor-widget elementor-widget-text-editor\" data-id=\"b7fe11c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stay ahead with insights, updates, and expert perspectives on the latest trends in Bluetooth technology and wireless communication.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d591dd3 elementor-widget elementor-widget-html\" data-id=\"d591dd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    body:not(.elementor-editor-active) .stagger-fade .stagger-grid-item {\n        opacity: 0;\n    }\n<\/style>\n\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/gsap@3.12.5\/dist\/gsap.min.js\"><\/script>\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/gsap@3.12.5\/dist\/ScrollTrigger.min.js\"><\/script>\n\n<script>\nconst staggerContainers = document.querySelectorAll('.stagger-fade');\n\nstaggerContainers.forEach(container => {\n  const gridItems = container.querySelectorAll('.stagger-grid-item');\n  \n  gsap.to(gridItems, {\n    opacity: 1,\n    duration: 0.4,\n    stagger: {\n      each: 0.25,\n      from: \"start\"\n    },\n    ease: \"none\",\n    scrollTrigger: {\n      trigger: container,\n      start: \"top bottom\",\n      toggleActions: \"play none none none\"\n    }\n  });\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anwendungen Ma\u00dfgeschneiderte Bluetooth LE L\u00f6sungen f\u00fcr deine Branchenanforderungen Wir entwickeln branchen-spezifische Bluetooth LE L\u00f6sungen, die alle deine Kommunikationsprobleme l\u00f6sen. Unsere Produkte bieten h\u00f6chste Leistung und Zuverl\u00e4ssigkeit, auch unter schwierigsten Bedingungen. Damit stellen wir sicher, dass dein System st\u00e4ndig zuverl\u00e4ssig, effizient und skalierbar bleibt. Entdecke die Vorteile unserer DEWINE Labs Technologie in verschiedenen Industrien. Gespr\u00e4ch buchen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2536","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dewinelabs.com\/de\/wp-json\/wp\/v2\/pages\/2536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dewinelabs.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dewinelabs.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dewinelabs.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dewinelabs.com\/de\/wp-json\/wp\/v2\/comments?post=2536"}],"version-history":[{"count":0,"href":"https:\/\/dewinelabs.com\/de\/wp-json\/wp\/v2\/pages\/2536\/revisions"}],"wp:attachment":[{"href":"https:\/\/dewinelabs.com\/de\/wp-json\/wp\/v2\/media?parent=2536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}